{"id":2270,"date":"2026-04-29T15:03:48","date_gmt":"2026-04-29T15:03:48","guid":{"rendered":"https:\/\/somosmosca.com.ar\/?post_type=product&#038;p=2270"},"modified":"2026-05-04T19:06:47","modified_gmt":"2026-05-04T19:06:47","slug":"anzuelo-mustad-s82-3906b","status":"publish","type":"product","link":"https:\/\/somosmosca.com.ar\/index.php\/producto\/anzuelo-mustad-s82-3906b\/","title":{"rendered":"ANZUELO MUSTAD S82 3906B x 50 unidades"},"content":{"rendered":"<p>La gran empresa que define anzuelos desde 1877. Serie Signature de mosca, fabricados en Noruega bajo los m\u00e1ximos standards de calidad.<\/p>\n<ul>\n<li><strong>Ojo:<\/strong>\u00a045 grados hacia abajo.<\/li>\n<li><strong>Punta:<\/strong>\u00a0afilado qu\u00edmico.<\/li>\n<li><strong>Alambre:<\/strong>\u00a03X strong.<\/li>\n<li><strong>Largo de pata:\u00a0<\/strong>2X long.<\/li>\n<li><strong>Terminaci\u00f3n:<\/strong>\u00a0tradicional bronce de agua dulce.<\/li>\n<li><strong>Revirado:<\/strong>\u00a0no.<\/li>\n<li><strong>Forjado:<\/strong>\u00a0si.<\/li>\n<li><strong>Aplicaci\u00f3n:<\/strong>\u00a0anzuelo\u00a0 de alambre grueso y pata media, ideal para moscas h\u00famedas, soft hackles, ninfas y wolly buggers. Ideal cuando se busca un anzuelo peque\u00f1o y robusto, que no se abra con truchas y salmones pesados (Ej: Strobel y TDF).<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La gran empresa que define anzuelos desde 1877. Serie Signature de mosca, fabricados en Noruega bajo los m\u00e1ximos standards de calidad. Ojo:\u00a045 grados hacia abajo. Punta:\u00a0afilado qu\u00edmico. Alambre:\u00a03X strong. Largo de pata:\u00a02X long. Terminaci\u00f3n:\u00a0tradicional bronce de agua dulce. Revirado:\u00a0no. Forjado:\u00a0si. Aplicaci\u00f3n:\u00a0anzuelo\u00a0 de alambre grueso y pata media, ideal para moscas h\u00famedas, soft hackles, ninfas y [&hellip;]<\/p>\n","protected":false},"featured_media":2274,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_joinchat":[]},"marca":[24],"product_brand":[235],"product_cat":[258,35],"product_tag":[236,237],"class_list":{"0":"post-2270","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"marca-mustad","7":"product_brand-mustad","8":"product_cat-anzuelos-fly-tying","9":"product_cat-fly-tying","10":"product_tag-anzuelo","11":"product_tag-mustad","12":"product_shipping_class-medianos","14":"first","15":"instock","16":"shipping-taxable","17":"purchasable","18":"product-type-variable"},"acf":[],"_links":{"self":[{"href":"https:\/\/somosmosca.com.ar\/index.php\/wp-json\/wp\/v2\/product\/2270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somosmosca.com.ar\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/somosmosca.com.ar\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/somosmosca.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=2270"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/somosmosca.com.ar\/index.php\/wp-json\/wp\/v2\/media\/2274"}],"wp:attachment":[{"href":"https:\/\/somosmosca.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=2270"}],"wp:term":[{"taxonomy":"marca","embeddable":true,"href":"https:\/\/somosmosca.com.ar\/index.php\/wp-json\/wp\/v2\/marca?post=2270"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/somosmosca.com.ar\/index.php\/wp-json\/wp\/v2\/product_brand?post=2270"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/somosmosca.com.ar\/index.php\/wp-json\/wp\/v2\/product_cat?post=2270"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/somosmosca.com.ar\/index.php\/wp-json\/wp\/v2\/product_tag?post=2270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}